{"id":25688,"date":"2025-10-15T15:26:19","date_gmt":"2025-10-15T13:26:19","guid":{"rendered":"https:\/\/www.factoria-4-7.org\/?post_type=recursos&#038;p=25688"},"modified":"2025-10-15T15:26:20","modified_gmt":"2025-10-15T13:26:20","slug":"les-llavors-de-berta-caceres-germinen","status":"publish","type":"recursos","link":"https:\/\/www.factoria-4-7.org\/gl\/recursos\/les-llavors-de-berta-caceres-germinen\/","title":{"rendered":"Les llavors de Berta C\u00e0ceres, germinen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Recurso educativo basado en la figura de Berta C\u00e1ceres, activista hondure\u00f1a, centrado en la justicia ambiental y el activismo en contextos de violencia.<\/p>\n","protected":false},"featured_media":25689,"template":"","ods":[10,7,18],"class_list":["post-25688","recursos","type-recursos","status-publish","has-post-thumbnail","hentry","ods-accion-clima","ods-paz-justicia-instituciones-solidas","ods-igualdad-genero"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.factoria-4-7.org\/gl\/wp-json\/wp\/v2\/recursos\/25688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.factoria-4-7.org\/gl\/wp-json\/wp\/v2\/recursos"}],"about":[{"href":"https:\/\/www.factoria-4-7.org\/gl\/wp-json\/wp\/v2\/types\/recursos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.factoria-4-7.org\/gl\/wp-json\/wp\/v2\/media\/25689"}],"wp:attachment":[{"href":"https:\/\/www.factoria-4-7.org\/gl\/wp-json\/wp\/v2\/media?parent=25688"}],"wp:term":[{"taxonomy":"ods","embeddable":true,"href":"https:\/\/www.factoria-4-7.org\/gl\/wp-json\/wp\/v2\/ods?post=25688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}